{"id":1368,"date":"2016-04-29T11:16:48","date_gmt":"2016-04-29T15:16:48","guid":{"rendered":"http:\/\/www.iestrie.com\/fr\/?page_id=1368"},"modified":"2021-05-09T17:46:53","modified_gmt":"2021-05-09T21:46:53","slug":"faq","status":"publish","type":"page","link":"https:\/\/www.invisibletranslation.com\/fr\/faq\/","title":{"rendered":"FAQ"},"content":{"rendered":"<p>[et_pb_section fb_built=\u00a0\u00bb1&Prime; custom_padding_last_edited=\u00a0\u00bbon|desktop\u00a0\u00bb admin_label=\u00a0\u00bbsection\u00a0\u00bb module_id=\u00a0\u00bbcontent-zone\u00a0\u00bb _builder_version=\u00a0\u00bb3.22&Prime; custom_padding_tablet=\u00a0\u00bb50px|0|50px|0&Prime; custom_padding_phone=\u00a0\u00bb\u00a0\u00bb transparent_background=\u00a0\u00bboff\u00a0\u00bb padding_mobile=\u00a0\u00bboff\u00a0\u00bb make_fullwidth=\u00a0\u00bboff\u00a0\u00bb use_custom_width=\u00a0\u00bboff\u00a0\u00bb width_unit=\u00a0\u00bbon\u00a0\u00bb][et_pb_row admin_label=\u00a0\u00bbrow\u00a0\u00bb _builder_version=\u00a0\u00bb3.25&Prime; background_size=\u00a0\u00bbinitial\u00a0\u00bb background_position=\u00a0\u00bbtop_left\u00a0\u00bb background_repeat=\u00a0\u00bbrepeat\u00a0\u00bb column_structure=\u00a0\u00bb2_3,1_3&Prime;][et_pb_column type=\u00a0\u00bb2_3&Prime; _builder_version=\u00a0\u00bb3.25&Prime; custom_padding=\u00a0\u00bb|||\u00a0\u00bb custom_padding__hover=\u00a0\u00bb|||\u00a0\u00bb][et_pb_text admin_label=\u00a0\u00bbBreadcrumb\u00a0\u00bb _builder_version=\u00a0\u00bb3.27.4&Prime; background_size=\u00a0\u00bbinitial\u00a0\u00bb background_position=\u00a0\u00bbtop_left\u00a0\u00bb background_repeat=\u00a0\u00bbrepeat\u00a0\u00bb use_border_color=\u00a0\u00bboff\u00a0\u00bb border_color=\u00a0\u00bb#ffffff\u00a0\u00bb border_style=\u00a0\u00bbsolid\u00a0\u00bb]<\/p>\n<p>\n<nav aria-label=\"breadcrumbs\" class=\"rank-math-breadcrumb\"><p><span class=\"last\">Home<\/span><\/p><\/nav><br \/>\n[\/et_pb_text][et_pb_text admin_label=\u00a0\u00bbLong Title\u00a0\u00bb _builder_version=\u00a0\u00bb3.27.4&Prime; background_size=\u00a0\u00bbinitial\u00a0\u00bb background_position=\u00a0\u00bbtop_left\u00a0\u00bb background_repeat=\u00a0\u00bbrepeat\u00a0\u00bb use_border_color=\u00a0\u00bboff\u00a0\u00bb border_color=\u00a0\u00bb#ffffff\u00a0\u00bb border_style=\u00a0\u00bbsolid\u00a0\u00bb]<\/p>\n<h1>Foire aux questions<\/h1>\n<p><img loading=\"lazy\" decoding=\"async\" id=\"title-top-image\" class=\"alignnone size-large wp-image-3302\" src=\"https:\/\/www.invisibletranslation.com\/wp-content\/uploads\/2016\/04\/FAQ-FR-1024x768.jpg\" alt=\"Foire aux questions\" width=\"1024\" height=\"768\" \/><\/p>\n<p>[\/et_pb_text][et_pb_text admin_label=\u00a0\u00bbMenu\u00a0\u00bb _builder_version=\u00a0\u00bb3.27.4&Prime; text_font=\u00a0\u00bbOpen Sans||||\u00a0\u00bb text_font_size=\u00a0\u00bb16&Prime; text_line_height=\u00a0\u00bb1.8em\u00a0\u00bb background_size=\u00a0\u00bbinitial\u00a0\u00bb background_position=\u00a0\u00bbtop_left\u00a0\u00bb background_repeat=\u00a0\u00bbrepeat\u00a0\u00bb use_border_color=\u00a0\u00bboff\u00a0\u00bb border_color=\u00a0\u00bb#ffffff\u00a0\u00bb border_style=\u00a0\u00bbsolid\u00a0\u00bb]<\/p>\n<p>\n1 &#8211; <a href=\"#renseignements\">Renseignements pratiques<\/a><br \/>\n2 &#8211; <a href=\"#equipe\">Notre \u00e9quipe<\/a><br \/>\n3 &#8211; <a href=\"#delais\">D\u00e9lais et tarifs<\/a><br \/>\n4 &#8211; <a href=\"#qualite\">Qualit\u00e9 et efficacit\u00e9<\/a><br \/>\n5 &#8211; <a href=\"#entreprise\">Notre entreprise<\/a><br \/>\n6 &#8211; <a href=\"#questions\">Autres questions<\/a><\/p>\n<p>[\/et_pb_text][et_pb_text admin_label=\u00a0\u00bb1 &#8211; RENSEIGNEMENTS PRATIQUES\u00a0\u00bb _builder_version=\u00a0\u00bb3.27.4&Prime; text_font=\u00a0\u00bbOpen Sans||||\u00a0\u00bb text_font_size=\u00a0\u00bb16&Prime; text_line_height=\u00a0\u00bb1.8em\u00a0\u00bb background_size=\u00a0\u00bbinitial\u00a0\u00bb background_position=\u00a0\u00bbtop_left\u00a0\u00bb background_repeat=\u00a0\u00bbrepeat\u00a0\u00bb use_border_color=\u00a0\u00bboff\u00a0\u00bb border_color=\u00a0\u00bb#ffffff\u00a0\u00bb border_style=\u00a0\u00bbsolid\u00a0\u00bb]<\/p>\n<p>\n<a name=\"renseignements\"><\/a><\/p>\n<h3 id=\"faq-001\">1 &#8211; RENSEIGNEMENTS PRATIQUES<\/h3>\n<p>[\/et_pb_text][et_pb_accordion _builder_version=\u00a0\u00bb4.9.4&Prime; hover_enabled=\u00a0\u00bb0&Prime; use_border_color=\u00a0\u00bboff\u00a0\u00bb border_color=\u00a0\u00bb#ffffff\u00a0\u00bb border_style=\u00a0\u00bbsolid\u00a0\u00bb sticky_enabled=\u00a0\u00bb0&Prime;][et_pb_accordion_item title=\u00a0\u00bbEst-ce que Traduction INVISIBLE est uniquement une agence de traduction?\u00a0\u00bb _builder_version=\u00a0\u00bb3.0.47&Prime; open=\u00a0\u00bbon\u00a0\u00bb]Non, Traduction INVISIBLE est bien plus qu\u2019une simple agence de traduction. Nous offrons des services de traduction, d\u2019adaptation publicitaire, de r\u00e9vision linguistique unilingue, de r\u00e9vision comparative bilingue, de correction d\u2019\u00e9preuves et de r\u00e9daction de textes. En fait, Traduction INVISIBLE est un regroupement de langagiers et de linguistes professionnels, amoureux des langues fran\u00e7aise, anglaise et espagnole, qui ont choisi de mettre leurs comp\u00e9tences en commun dans le but de vous offrir une vari\u00e9t\u00e9 de services linguistiques de qualit\u00e9.<br \/>\n[\/et_pb_accordion_item][et_pb_accordion_item title=\u00a0\u00bbQuelles sont les combinaisons de langue que vous traduisez?\u00a0\u00bb _builder_version=\u00a0\u00bb3.0.47&Prime; open=\u00a0\u00bboff\u00a0\u00bb]Fran\u00e7ais \u2192 Anglais<br \/>\nFran\u00e7ais \u2192 Espagnol<br \/>\nAnglais \u2192 Fran\u00e7ais<br \/>\nAnglais \u2192 Espagnol<br \/>\nEspagnol \u2192 Fran\u00e7ais<br \/>\nEspagnol \u2192 Anglais<br \/>\n[\/et_pb_accordion_item][et_pb_accordion_item title=\u00a0\u00bbQuels sont les champs de comp\u00e9tence des membres de votre \u00e9quipe?\u00a0\u00bb _builder_version=\u00a0\u00bb3.0.47&Prime; open=\u00a0\u00bboff\u00a0\u00bb]Ils sont nombreux. Voici quelques-uns de nos domaines de pr\u00e9dilection\u00a0: les technologies de l\u2019environnement; la publicit\u00e9 et le marketing; l\u2019informatique; la psychologie organisationnelle; le commerce et l\u2019\u00e9conomie; l\u2019immobilier; l\u2019administration; l\u2019\u00e9ducation; le sport; l\u2019\u0153nologie et la viticulture; la min\u00e9ralurgie, le traitement de minerai et l\u2019exploitation mini\u00e8re.<br \/>\n[\/et_pb_accordion_item][et_pb_accordion_item title=\u00a0\u00bbJ\u2019aimerais faire appel \u00e0 vos services. Que dois-je faire?\u00a0\u00bb _builder_version=\u00a0\u00bb3.0.47&Prime; open=\u00a0\u00bboff\u00a0\u00bb]Rien de plus simple. Vous n\u2019avez qu\u2019\u00e0 cliquer sur <a href=\"https:\/\/www.invisibletranslation.com\/fr\/contact\/formulaire-offre-de-service\/\">ce lien<\/a> et \u00e0 remplir le formulaire qui appara\u00eetra \u00e0 l\u2019\u00e9cran. Vous pouvez \u00e9galement nous faire parvenir vos documents et les renseignements pertinents \u00e0 cette adresse\u00a0:\u00a0<a href=\"mailto:offredeservice@traductioninvisible.com?subject=Demande%20de%20devis%20-%20FAQ&amp;body=*Tous%20les%20champs%20doivent%20%C3%AAtre%20remplis.*%20%0A%0ANom%20:%0AFonction%20:%20%0ASoci%C3%A9t%C3%A9%20:%0AAdresse%20postale%20:%0A%0AT%C3%A9l%C3%A9phone%20:%0AT%C3%A9l%C3%A9copieur%20:%0ACourriel%20:%0A%0ALangue(s)%20d%E2%80%99origine%20:%0ALangue(s)%20d%E2%80%99arriv%C3%A9e%20\/%20pays%20:%0A%0AFichier(s)%20:%0AVotre%20num%C3%A9ro%20de%20r%C3%A9f%C3%A9rence%20:%0A%0ARemarques%20et%20consignes%20:%0A%0A%0A%3E%3E%3E%20N%E2%80%99OUBLIEZ%20PAS%20DE%20JOINDRE%20VOS%20FICHIERS%20ET%20DE%20PR%C3%89CISER%20LE%20D%C3%89LAI%20QUE%20VOUS%20NOUS%20ACCORDEZ.%0A\">offredeservice@traductioninvisible.com<\/a>.<\/p>\n<p>N\u2019oubliez pas de\u00a0:<\/p>\n<ol>\n<li>nous pr\u00e9senter clairement vos besoins;<\/li>\n<li>fixer le d\u00e9lai que vous nous accordez pour effectuer les travaux;<\/li>\n<li>nous soumettre les documents dont nous aurons besoin pour r\u00e9aliser le mandat.<\/li>\n<\/ol>\n<p>Une fois que ces modalit\u00e9s auront \u00e9t\u00e9 d\u00e9finies, nous vous ferons parvenir gratuitement une offre de service en moins de 24 heures sans que cela vous engage \u00e0 quoi que ce soit. Si le temps presse, t\u00e9l\u00e9phonez \u00e0 nos bureaux en composant le num\u00e9ro suivant\u00a0: <a href=\"tel:18334366331\">+1\u00a0833-436-6331<\/a>.<br \/>\n[\/et_pb_accordion_item][et_pb_accordion_item title=\u00a0\u00bbComment puis-je vous transmettre les documents dont vous aurez besoin pour \u00e9tablir l&rsquo;offre de service?\u00a0\u00bb _builder_version=\u00a0\u00bb3.0.47&Prime; open=\u00a0\u00bboff\u00a0\u00bb]Vous pouvez nous transmettre vos documents par <a href=\"mailto:offredeservice@traductioninvisible.com?subject=Demande%20de%20devis%20-%20FAQ&amp;body=*Tous%20les%20champs%20doivent%20%C3%AAtre%20remplis.*%20%0A%0ANom%20:%0AFonction%20:%20%0ASoci%C3%A9t%C3%A9%20:%0AAdresse%20postale%20:%0A%0AT%C3%A9l%C3%A9phone%20:%0AT%C3%A9l%C3%A9copieur%20:%0ACourriel%20:%0A%0ALangue(s)%20d%E2%80%99origine%20:%0ALangue(s)%20d%E2%80%99arriv%C3%A9e%20\/%20pays%20:%0A%0AFichier(s)%20:%0AVotre%20num%C3%A9ro%20de%20r%C3%A9f%C3%A9rence%20:%0A%0ARemarques%20et%20consignes%20:%0A%0A%0A%3E%3E%3E%20N%E2%80%99OUBLIEZ%20PAS%20DE%20JOINDRE%20VOS%20FICHIERS%20ET%20DE%20PR%C3%89CISER%20LE%20D%C3%89LAI%20QUE%20VOUS%20NOUS%20ACCORDEZ.%0A\">courrier \u00e9lectronique<\/a>, par t\u00e9l\u00e9copieur, par la poste, par courrier recommand\u00e9 ou par messagerie. Vous pouvez \u00e9galement nous les envoyer par ce <a href=\"https:\/\/www.invisibletranslation.com\/fr\/contact\/formulaire-offre-de-service\/\">formulaire<\/a> ou nous les remettre en main propre en vous rendant \u00e0 nos bureaux.<br \/>\n[\/et_pb_accordion_item][et_pb_accordion_item title=\u00a0\u00bbDe combien de temps avez-vous besoin pour \u00e9valuer l\u2019envergure des travaux et me transmettre l&rsquo;offre de service?\u00a0\u00bb _builder_version=\u00a0\u00bb3.0.47&Prime; open=\u00a0\u00bboff\u00a0\u00bb]Moins de 24\u00a0heures. Nous vous ferons parvenir notre offre de service par courrier \u00e9lectronique ou par t\u00e9l\u00e9copieur le plus rapidement possible, en moins d\u2019une heure habituellement.<br \/>\n[\/et_pb_accordion_item][et_pb_accordion_item title=\u00a0\u00bbQuelles sont les modalit\u00e9s de paiement?\u00a0\u00bb _builder_version=\u00a0\u00bb3.0.47&Prime; open=\u00a0\u00bboff\u00a0\u00bb]Vous pouvez nous faire parvenir un ch\u00e8que certifi\u00e9 ou une traite bancaire par la poste, par courrier recommand\u00e9 ou par messagerie. Vous pouvez \u00e9galement effectuer un transfert de fonds, un virement par courriel ou un virement t\u00e9l\u00e9graphique vers notre compte d\u2019entreprise. Nous acceptons aussi les paiements par carte de cr\u00e9dit par l\u2019entremise de Square et du site s\u00e9curis\u00e9 <a href=\"https:\/\/www.paypal.com\/ca\/webapps\/mpp\/home?locale.x=fr_CA\" target=\"_blank\" rel=\"noopener noreferrer nofollow\">PayPal<\/a>.<br \/>\n[\/et_pb_accordion_item][et_pb_accordion_item title=\u00a0\u00bbEst-ce que vous m\u2019offrez un escompte si j\u2019acquitte rapidement ma facture? \u00a0\u00bb _builder_version=\u00a0\u00bb3.0.47&Prime; open=\u00a0\u00bboff\u00a0\u00bb]Oui. Si vous payez la totalit\u00e9 de la facture dans les dix (10) jours suivant la date de facturation, nous porterons \u00e0 votre compte un cr\u00e9dit qui correspond \u00e0 deux pour cent (2\u00a0%) du montant de la facture que vous aurez acquitt\u00e9e promptement.<br \/>\n[\/et_pb_accordion_item][et_pb_accordion_item title=\u00a0\u00bbDonc, vous d\u00e9duirez ce cr\u00e9dit de deux pour cent (2 %) de ma prochaine facture?\u00a0\u00bb _builder_version=\u00a0\u00bb3.0.47&Prime; open=\u00a0\u00bboff\u00a0\u00bb]C\u2019est exact. Supposons que la facture du projet A s\u2019\u00e9l\u00e8ve \u00e0 1\u00a0000\u00a0$ et que vous l\u2019acquittez en entier dans les dix (10) jours suivant la date \u00e0 laquelle la facture a \u00e9t\u00e9 \u00e9mise. Nous porterons alors \u00e0 votre compte un cr\u00e9dit de 20\u00a0$ (soit 2 % de 1\u00a0000\u00a0$), qui sera d\u00e9duit de la facture du projet B.<br \/>\n[\/et_pb_accordion_item][et_pb_accordion_item title=\u00a0\u00bbEst-ce que vous offrez un tarif pr\u00e9f\u00e9rentiel aux organismes \u00e0 but non lucratif et aux organismes de bienfaisance?\u00a0\u00bb _builder_version=\u00a0\u00bb3.0.47&Prime; open=\u00a0\u00bboff\u00a0\u00bb]Oui. Nous offrons une r\u00e9duction de trois pour cent (3 %) aux organismes sans but lucratif inscrits au Registre des entreprises du Qu\u00e9bec et aux organismes de bienfaisance enregistr\u00e9s aupr\u00e8s de l\u2019Agence du revenu du Canada.<br \/>\n[\/et_pb_accordion_item][et_pb_accordion_item title=\u00a0\u00bbEst-ce que vous offrez un tarif pr\u00e9f\u00e9rentiel aux organismes vou\u00e9s \u00e0 la d\u00e9fense de l\u2019environnement?\u00a0\u00bb _builder_version=\u00a0\u00bb3.0.47&Prime; open=\u00a0\u00bboff\u00a0\u00bb]Nous offrons une r\u00e9duction de trois pour cent (3 %) aux entreprises \u00e9cocertifi\u00e9es et aux membres des r\u00e9seaux provinciaux affili\u00e9s au R\u00e9seau canadien de l\u2019environnement.<br \/>\n[\/et_pb_accordion_item][et_pb_accordion_item title=\u00a0\u00bbPourquoi avoir \u00e9tabli un tarif minimal?\u00a0\u00bb _builder_version=\u00a0\u00bb4.9.4&Prime; hover_enabled=\u00a0\u00bb0&Prime; open=\u00a0\u00bboff\u00a0\u00bb sticky_enabled=\u00a0\u00bb0&Prime;]La mise en place d\u2019un seuil bien d\u00e9fini pour l\u2019ensemble de nos clients s\u2019explique par de nombreuses raisons. M\u00eame si une demande de service comporte uniquement quelques mots, nous devons malgr\u00e9 tout r\u00e9diger et \u00e9changer des courriers \u00e9lectroniques, t\u00e9l\u00e9charger des fichiers et les archiver, consigner les d\u00e9tails du mandat dans notre banque de donn\u00e9es, assigner la t\u00e2che \u00e0 nos langagiers, effectuer les recherches requises, lire de la documentation connexe, r\u00e9viser notre travail avant de le rendre au client, pr\u00e9parer la facture, et parfois r\u00e9pondre \u00e0 des questions apr\u00e8s la remise. Tout cela prend du temps.[\/et_pb_accordion_item][et_pb_accordion_item title=\u00a0\u00bbSi j\u2019ai une question pendant les travaux?\u00a0\u00bb _builder_version=\u00a0\u00bb3.0.47&Prime; open=\u00a0\u00bboff\u00a0\u00bb]Communiquez par t\u00e9l\u00e9phone ou par courrier \u00e9lectronique durant les heures d\u2019ouverture de notre agence avec le directeur de projet qui s\u2019occupe de votre dossier. Ce dernier se fera un plaisir de r\u00e9pondre \u00e0 toutes vos questions. Si vous n\u2019\u00eates pas en mesure de joindre cette personne, vous n\u2019avez qu\u2019\u00e0 t\u00e9l\u00e9phoner au <a href=\"tel:18334366331\">+1\u00a0833-436-6331<\/a>.<br \/>\n[\/et_pb_accordion_item][\/et_pb_accordion][et_pb_text admin_label=\u00a0\u00bb2 &#8211; NOTRE \u00c9QUIPE\u00a0\u00bb _builder_version=\u00a0\u00bb3.27.4&Prime; text_font=\u00a0\u00bbOpen Sans||||\u00a0\u00bb text_font_size=\u00a0\u00bb16&Prime; text_line_height=\u00a0\u00bb1.8em\u00a0\u00bb background_size=\u00a0\u00bbinitial\u00a0\u00bb background_position=\u00a0\u00bbtop_left\u00a0\u00bb background_repeat=\u00a0\u00bbrepeat\u00a0\u00bb use_border_color=\u00a0\u00bboff\u00a0\u00bb border_color=\u00a0\u00bb#ffffff\u00a0\u00bb border_style=\u00a0\u00bbsolid\u00a0\u00bb]<\/p>\n<p>\n<a name=\"equipe\"><\/a><\/p>\n<h3 id=\"faq-002\">2 &#8211; NOTRE \u00c9QUIPE<\/h3>\n<p>[\/et_pb_text][et_pb_accordion _builder_version=\u00a0\u00bb3.0.87&Prime; use_border_color=\u00a0\u00bboff\u00a0\u00bb border_color=\u00a0\u00bb#ffffff\u00a0\u00bb border_style=\u00a0\u00bbsolid\u00a0\u00bb][et_pb_accordion_item title=\u00a0\u00bbEst-ce que les traducteurs de votre \u00e9quipe sont membres d\u2019une association professionnelle canadienne?\u00a0\u00bb _builder_version=\u00a0\u00bb3.0.47&Prime; open=\u00a0\u00bbon\u00a0\u00bb] La grande majorit\u00e9 des langagiers qui travaillent \u00e0 titre de traducteur au sein de notre agence de traduction sont membres de l\u2019Ordre des traducteurs, terminologues et interpr\u00e8tes agr\u00e9\u00e9s du Qu\u00e9bec (OTTIAQ), de l&rsquo;Association des traducteurs et interpr\u00e8tes de l&rsquo;Ontario (ATIO) ou d\u2019un autre regroupement de traducteurs professionnels reconnu par le Conseil des traducteurs, terminologues et interpr\u00e8tes du Canada (CTTIC). Certains de nos coll\u00e8gues sont aussi membres d\u2019associations \u00e9trang\u00e8res, comme l\u2019<em>American Translators Association<\/em> (ATA) des \u00c9tats-Unis, ou le <em>Chartered Institute of Linguists<\/em> (CIOL) du Royaume-Uni.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<br \/>\n[\/et_pb_accordion_item][et_pb_accordion_item title=\u00a0\u00bbEst-ce que c\u2019est \u00e9galement le cas de vos r\u00e9viseurs et de vos correcteurs d\u2019\u00e9preuves?\u00a0\u00bb _builder_version=\u00a0\u00bb3.0.47&Prime; open=\u00a0\u00bboff\u00a0\u00bb]Plusieurs de nos r\u00e9viseurs et de nos correcteurs d\u2019\u00e9preuves sont membres de R\u00e9viseurs Canada (RC). Nous faisons aussi appel \u00e0 des traducteurs chevronn\u00e9s pour r\u00e9viser les travaux produits par les membres de notre \u00e9quipe. Cette d\u00e9marche s\u2019inscrit dans le cadre du processus de contr\u00f4le de la qualit\u00e9 que Traduction INVISIBLE a mis en place.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<br \/>\n[\/et_pb_accordion_item][et_pb_accordion_item title=\u00a0\u00bbQu\u2019en est-il de vos r\u00e9dacteurs?\u00a0\u00bb _builder_version=\u00a0\u00bb3.0.47&Prime; open=\u00a0\u00bboff\u00a0\u00bb]Plusieurs de nos r\u00e9dacteurs sont membres de la Soci\u00e9t\u00e9 qu\u00e9b\u00e9coise de la r\u00e9daction professionnelle. Forts de leur solide exp\u00e9rience, ces derniers connaissent les rouages du m\u00e9tier et disposent d\u2019excellentes comp\u00e9tences r\u00e9dactionnelles, ce qui leur permet de r\u00e9diger des textes fluides, coh\u00e9rents et impeccables.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<br \/>\n[\/et_pb_accordion_item][et_pb_accordion_item title=\u00a0\u00bbQu\u2019est-ce qui distingue le travail d\u2019un professionnel de celui d\u2019un non-initi\u00e9?\u00a0\u00bb _builder_version=\u00a0\u00bb3.0.47&Prime; open=\u00a0\u00bboff\u00a0\u00bb] Mentionnons la fluidit\u00e9 des phrases, l\u2019encha\u00eenement logique du contenu, la lisibilit\u00e9 du texte, l\u2019utilisation judicieuse des marqueurs de relation et des cooccurrents, la concordance des temps grammaticaux, le respect de l\u2019usage, sans oublier l\u2019absence d\u2019anglicismes, de barbarismes, de faux amis, d\u2019impropri\u00e9t\u00e9s, d\u2019interf\u00e9rences, de sol\u00e9cismes et de zeugmes.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<br \/>\n[\/et_pb_accordion_item][\/et_pb_accordion][et_pb_text admin_label=\u00a0\u00bb3 &#8211; D\u00c9LAIS ET TARIFS\u00a0\u00bb _builder_version=\u00a0\u00bb3.27.4&Prime; text_font=\u00a0\u00bbOpen Sans||||\u00a0\u00bb text_font_size=\u00a0\u00bb16&Prime; text_line_height=\u00a0\u00bb1.8em\u00a0\u00bb background_size=\u00a0\u00bbinitial\u00a0\u00bb background_position=\u00a0\u00bbtop_left\u00a0\u00bb background_repeat=\u00a0\u00bbrepeat\u00a0\u00bb use_border_color=\u00a0\u00bboff\u00a0\u00bb border_color=\u00a0\u00bb#ffffff\u00a0\u00bb border_style=\u00a0\u00bbsolid\u00a0\u00bb]<\/p>\n<p>\n<a name=\"delais\"><\/a><\/p>\n<h3 id=\"faq-003\">3 &#8211; D\u00c9LAIS ET TARIFS<\/h3>\n<p>[\/et_pb_text][et_pb_text admin_label=\u00a0\u00bbServices professionnels de traduction\u00a0\u00bb _builder_version=\u00a0\u00bb3.27.4&Prime; background_size=\u00a0\u00bbinitial\u00a0\u00bb background_position=\u00a0\u00bbtop_left\u00a0\u00bb background_repeat=\u00a0\u00bbrepeat\u00a0\u00bb use_border_color=\u00a0\u00bboff\u00a0\u00bb border_color=\u00a0\u00bb#ffffff\u00a0\u00bb border_style=\u00a0\u00bbsolid\u00a0\u00bb]<\/p>\n<p>\n<strong>Services professionnels de traduction<\/strong><\/p>\n<p>[\/et_pb_text][et_pb_accordion _builder_version=\u00a0\u00bb3.22.1&Prime; z_index_tablet=\u00a0\u00bb500&Prime; use_border_color=\u00a0\u00bboff\u00a0\u00bb][et_pb_accordion_item title=\u00a0\u00bbDe combien de temps avez-vous besoin pour traduire un document?\u00a0\u00bb _builder_version=\u00a0\u00bb3.22.1&Prime; open=\u00a0\u00bbon\u00a0\u00bb]Cela d\u00e9pend surtout de sa nature (scientifique, technique, administratif, etc.) et du nombre de mots que compte celui-ci. \u00c0 titre informatif, chaque traducteur de notre \u00e9quipe est capable de traduire quotidiennement 1&nbsp;500 mots \u00e0 2&nbsp;000&nbsp;mots de qualit\u00e9 professionnelle.<br \/>\n[\/et_pb_accordion_item][et_pb_accordion_item title=\u00a0\u00bbDe quelle fa\u00e7on \u00e9tablissez-vous le co\u00fbt de vos services lorsque vous devez traduire un texte?\u00a0\u00bb _builder_version=\u00a0\u00bb3.22.1&Prime; open=\u00a0\u00bboff\u00a0\u00bb]Nous \u00e9tablissons le co\u00fbt de nos services de traduction en fonction d\u2019une grille d\u2019\u00e9valuation qui tient compte de nombreux crit\u00e8res, notamment du nombre de mots que compte le document que vous nous demandez de traduire, du d\u00e9lai que vous nous accordez, du format (.doc, .pdf, .pub, .indd, etc.) de vos fichiers \u00e9lectroniques, etc. Nous fixons alors un tarif par mot et nous multiplions ce tarif par le nombre de mots que compte votre texte.<br \/>\n[\/et_pb_accordion_item][et_pb_accordion_item title=\u00a0\u00bbEst-ce que vos services de traduction sont factur\u00e9s uniquement en fonction d\u2019un tarif par mot?\u00a0\u00bb _builder_version=\u00a0\u00bb3.22.1&Prime; open=\u00a0\u00bboff\u00a0\u00bb]Pas forc\u00e9ment. Nous utilisons plut\u00f4t un tarif horaire lorsque nous travaillons avec des fichiers qui demandent des manipulations, comme les pr\u00e9sentations PowerPoint ou les documents dont des sections sont d\u00e9j\u00e0 traduites. Le m\u00eame principe s\u2019applique lorsque nous devons traduire des documents officiels (acte de naissance, certificat de mariage, permis de conduire, relev\u00e9 de notes, etc.), lesquels exigent un important travail de mise en page pour reconstituer la disposition du document d\u2019origine. Nos services de traduction publicitaire sont aussi factur\u00e9s selon un tarif horaire, puisque l\u2019adaptation d\u2019un slogan de trois mots, par exemple, ne peut se faire en seulement quelques minutes. Dans de tels cas, la facturation par mot n\u2019est tout simplement pas appropri\u00e9e.<br \/>\n[\/et_pb_accordion_item][et_pb_accordion_item title=\u00a0\u00bbEst-ce vous traduisez des documents dits \u00ab officiels \u00bb?\u00a0\u00bb _builder_version=\u00a0\u00bb3.22.1&Prime; open=\u00a0\u00bboff\u00a0\u00bb]<\/p>\n<p>Oui, nous produisons des traductions certifi\u00e9es \u00e0 des fins officielles, parfois appel\u00e9es \u00e0 tort des traductions asserment\u00e9es, qui sont reconnues et accept\u00e9es par l\u2019\u00c9tat. La traduction d\u2019un document officiel est un exercice complexe, car nous devons recr\u00e9er la disposition du document d\u2019origine, ajouter les sceaux et les signatures, valider la concordance des num\u00e9ros et des renseignements, signer et parapher chaque page, puis pr\u00e9parer une attestation solennelle bilingue. <a href=\"https:\/\/www.invisibletranslation.com\/fr\/services\/traduction\/documents-officiels\/\">Cette page<\/a> vous en dira plus.<\/p>\n<p>[\/et_pb_accordion_item][\/et_pb_accordion][et_pb_text admin_label=\u00a0\u00bbServices professionnels de r\u00e9vision et de correction d\u2019\u00e9preuves\u00a0\u00bb _builder_version=\u00a0\u00bb3.27.4&Prime; background_size=\u00a0\u00bbinitial\u00a0\u00bb background_position=\u00a0\u00bbtop_left\u00a0\u00bb background_repeat=\u00a0\u00bbrepeat\u00a0\u00bb use_border_color=\u00a0\u00bboff\u00a0\u00bb border_color=\u00a0\u00bb#ffffff\u00a0\u00bb border_style=\u00a0\u00bbsolid\u00a0\u00bb]<\/p>\n<p>\n<strong>Services professionnels de r\u00e9vision et de correction d\u2019\u00e9preuves<\/strong><\/p>\n<p>[\/et_pb_text][et_pb_accordion _builder_version=\u00a0\u00bb3.0.87&Prime; use_border_color=\u00a0\u00bboff\u00a0\u00bb border_color=\u00a0\u00bb#ffffff\u00a0\u00bb border_style=\u00a0\u00bbsolid\u00a0\u00bb][et_pb_accordion_item title=\u00a0\u00bbDe combien de temps avez-vous besoin pour r\u00e9viser ou pour corriger un document?\u00a0\u00bb _builder_version=\u00a0\u00bb3.0.47&Prime; open=\u00a0\u00bbon\u00a0\u00bb]Cela d\u00e9pend de la qualit\u00e9 de la r\u00e9daction du texte que nous devons r\u00e9viser ou corriger, de la nature de celui-ci, de son degr\u00e9 de technicit\u00e9 et du nombre de mots qu\u2019il compte. En effet, une cession de droits de 5\u00a0000\u00a0mots est g\u00e9n\u00e9ralement plus longue \u00e0 r\u00e9viser ou \u00e0 corriger qu\u2019un programme de formation qui contient le m\u00eame nombre de mots. Par ailleurs, un texte bien r\u00e9dig\u00e9 est plus facile \u00e0 r\u00e9viser ou \u00e0 corriger qu\u2019un texte pr\u00e9par\u00e9 \u00e0 la h\u00e2te. De plus, prenez note que le processus de r\u00e9vision est plus laborieux si le document que vous nous soumettez a \u00e9t\u00e9 traduit pr\u00e9alablement, puisque nous devons comparer la version traduite avec le document d\u2019origine.[\/et_pb_accordion_item][et_pb_accordion_item title=\u00a0\u00bbDe quelle fa\u00e7on \u00e9tablissez-vous le co\u00fbt de vos services lorsque vous devez r\u00e9viser ou corriger un texte?\u00a0\u00bb _builder_version=\u00a0\u00bb3.0.47&Prime; open=\u00a0\u00bboff\u00a0\u00bb]Nous \u00e9tablissons le co\u00fbt de nos\u00a0services de r\u00e9vision ou de correction d&rsquo;\u00e9preuves en multipliant notre tarif horaire par le nombre d\u2019heures dont nous aurons besoin pour effectuer une r\u00e9vision rigoureuse et une correction syst\u00e9matique de ce texte.[\/et_pb_accordion_item][et_pb_accordion_item title=\u00a0\u00bbEst-ce que vos services de r\u00e9vision et de correction d\u2019\u00e9preuves sont factur\u00e9s uniquement en fonction d\u2019un tarif horaire?\u00a0\u00bb _builder_version=\u00a0\u00bb3.0.47&Prime; open=\u00a0\u00bboff\u00a0\u00bb]Pas forc\u00e9ment. Nous fixons un tarif par mot lorsque nous entreprenons la r\u00e9vision ou la correction d\u2019un document volumineux qui s\u2019\u00e9chelonnera sur plusieurs semaines, ce qui permet \u00e0 nos clients de conna\u00eetre d\u2019embl\u00e9e le co\u00fbt des travaux. Nous nous servons d\u2019une grille d\u2019\u00e9valuation qui tient compte de nombreux crit\u00e8res (langue de travail, qualit\u00e9 de la r\u00e9daction, nombre de mots, nature du texte, degr\u00e9 de technicit\u00e9, etc.) pour \u00e9tablir notre tarif et nous multiplions celui-ci par le nombre de mots que compte le texte que nous devons r\u00e9viser ou corriger.[\/et_pb_accordion_item][\/et_pb_accordion][et_pb_text admin_label=\u00a0\u00bbServices professionnels de r\u00e9daction\u00a0\u00bb _builder_version=\u00a0\u00bb3.27.4&Prime; background_size=\u00a0\u00bbinitial\u00a0\u00bb background_position=\u00a0\u00bbtop_left\u00a0\u00bb background_repeat=\u00a0\u00bbrepeat\u00a0\u00bb use_border_color=\u00a0\u00bboff\u00a0\u00bb border_color=\u00a0\u00bb#ffffff\u00a0\u00bb border_style=\u00a0\u00bbsolid\u00a0\u00bb]<\/p>\n<p>\n<strong>Services professionnels de r\u00e9daction<\/strong><\/p>\n<p>[\/et_pb_text][et_pb_accordion _builder_version=\u00a0\u00bb3.0.87&Prime; use_border_color=\u00a0\u00bboff\u00a0\u00bb border_color=\u00a0\u00bb#ffffff\u00a0\u00bb border_style=\u00a0\u00bbsolid\u00a0\u00bb][et_pb_accordion_item title=\u00a0\u00bbDe combien de temps avez-vous besoin pour r\u00e9diger un texte?\u00a0\u00bb _builder_version=\u00a0\u00bb3.0.47&Prime; open=\u00a0\u00bbon\u00a0\u00bb]Cela d\u00e9pend du type de texte qui doit \u00eatre r\u00e9dig\u00e9, de la longueur pr\u00e9vue et du travail de recherche qui doit \u00eatre fait avant d\u2019entreprendre la r\u00e9daction \u00e0 proprement parler. Par exemple, la pr\u00e9paration d\u2019un communiqu\u00e9 de presse ne pose pas les m\u00eames difficult\u00e9s que la r\u00e9daction d\u2019un manuel d\u2019utilisation technique.[\/et_pb_accordion_item][et_pb_accordion_item title=\u00a0\u00bbDe quelle fa\u00e7on \u00e9tablissez-vous le co\u00fbt de vos services lorsque vous devez r\u00e9diger un texte?\u00a0\u00bb _builder_version=\u00a0\u00bb3.0.47&Prime; open=\u00a0\u00bboff\u00a0\u00bb]Nous \u00e9tablissons le co\u00fbt de nos services de r\u00e9daction en multipliant notre tarif horaire par le nombre d\u2019heures dont nous aurons besoin pour effectuer le travail de recherche, la r\u00e9daction du texte et la r\u00e9vision de celui-ci.[\/et_pb_accordion_item][et_pb_accordion_item title=\u00a0\u00bbQuels types de textes \u00eates-vous en mesure de r\u00e9diger?\u00a0\u00bb _builder_version=\u00a0\u00bb3.0.47&Prime; open=\u00a0\u00bboff\u00a0\u00bb]Nos r\u00e9dacteurs sont appel\u00e9s \u00e0 r\u00e9diger des documents administratifs et techniques des plus vari\u00e9s\u00a0: brochures commerciales, cahiers de charges, communiqu\u00e9s de presse, comptes rendus, d\u00e9pliants publicitaires, directives, dossiers de candidature, dossiers de pr\u00e9sentation, fiches d\u2019instruction, manuels d\u2019entretien, manuels d\u2019utilisation, notes de service, notes techniques, offres d\u2019emploi, offres de service, proc\u00e9d\u00e9s, programmes de travail, et plus encore.[\/et_pb_accordion_item][\/et_pb_accordion][et_pb_text admin_label=\u00a0\u00bb4 &#8211; QUALIT\u00c9 ET EFFICACIT\u00c9\u00a0\u00bb _builder_version=\u00a0\u00bb3.27.4&Prime; text_font=\u00a0\u00bbOpen Sans||||\u00a0\u00bb text_font_size=\u00a0\u00bb16&Prime; text_line_height=\u00a0\u00bb1.8em\u00a0\u00bb background_size=\u00a0\u00bbinitial\u00a0\u00bb background_position=\u00a0\u00bbtop_left\u00a0\u00bb background_repeat=\u00a0\u00bbrepeat\u00a0\u00bb use_border_color=\u00a0\u00bboff\u00a0\u00bb border_color=\u00a0\u00bb#ffffff\u00a0\u00bb border_style=\u00a0\u00bbsolid\u00a0\u00bb]<\/p>\n<p>\n<a name=\"qualite\"><\/a><\/p>\n<h3 id=\"faq-004\">4 &#8211; QUALIT\u00c9 ET EFFICACIT\u00c9<\/h3>\n<p>[\/et_pb_text][et_pb_accordion _builder_version=\u00a0\u00bb3.0.87&Prime; use_border_color=\u00a0\u00bboff\u00a0\u00bb border_color=\u00a0\u00bb#ffffff\u00a0\u00bb border_style=\u00a0\u00bbsolid\u00a0\u00bb][et_pb_accordion_item title=\u00a0\u00bbAvez-vous mis en place des m\u00e9canismes de contr\u00f4le de la qualit\u00e9?\u00a0\u00bb _builder_version=\u00a0\u00bb3.0.47&Prime; open=\u00a0\u00bbon\u00a0\u00bb] Oui. Chaque projet que nous r\u00e9alisons est cautionn\u00e9 par notre \u00e9quipe de r\u00e9viseurs et de correcteurs d\u2019\u00e9preuves afin d\u2019assurer un contr\u00f4le rigoureux de la qualit\u00e9. C\u2019est donc dire que le document que nous avons traduit, adapt\u00e9 ou r\u00e9dig\u00e9 conform\u00e9ment \u00e0 vos exigences est ensuite pass\u00e9 en revue par un des r\u00e9viseurs de notre \u00e9quipe. En portant un regard neuf sur le texte, le r\u00e9viseur peut ainsi l\u2019analyser minutieusement et rectifier, le cas \u00e9ch\u00e9ant, le style et le contenu de celui-ci. [\/et_pb_accordion_item][et_pb_accordion_item title=\u00a0\u00bbDe quelle fa\u00e7on vous assurez-vous que le document traduit est conforme \u00e0 l\u2019original?\u00a0\u00bb _builder_version=\u00a0\u00bb3.0.47&Prime; open=\u00a0\u00bboff\u00a0\u00bb] Lorsque l\u2019\u00e9tape de la traduction est termin\u00e9e, un de nos r\u00e9viseurs v\u00e9rifie l\u2019exactitude de la version traduite et l\u2019\u00e9quivalence des deux documents en les pla\u00e7ant c\u00f4te \u00e0 c\u00f4te pour comparer chaque phrase du texte d\u2019origine avec sa traduction. Le r\u00e9viseur apporte alors, au besoin, les corrections n\u00e9cessaires afin que le texte traduit r\u00e9ponde aux rigoureuses normes de qualit\u00e9 que notre \u00e9quipe a \u00e9tablies. [\/et_pb_accordion_item][et_pb_accordion_item title=\u00a0\u00bbComment les travaux sont-ils r\u00e9partis entre les membres de votre \u00e9quipe?\u00a0\u00bb _builder_version=\u00a0\u00bb3.0.47&Prime; open=\u00a0\u00bboff\u00a0\u00bb] Pour commencer, un de nos directeurs de projet analyse attentivement la nature du mandat qui nous est confi\u00e9. Ce dernier forme ensuite une \u00e9quipe de langagiers qui conna\u00eet parfaitement le domaine de sp\u00e9cialit\u00e9 dont il est question. Dans le cas d\u2019un projet de traduction, les traducteurs qui sont choisis sont aussi des locuteurs natifs de la langue vers laquelle le texte doit \u00eatre traduit. [\/et_pb_accordion_item][et_pb_accordion_item title=\u00a0\u00bbQu\u2019entendez-vous par \u00ab locuteur natif \u00bb?\u00a0\u00bb _builder_version=\u00a0\u00bb3.0.47&Prime; open=\u00a0\u00bboff\u00a0\u00bb]Nous dirons d\u2019une personne qu\u2019elle est <em>locutrice native<\/em> du fran\u00e7ais si la langue fran\u00e7aise est la premi\u00e8re qu&rsquo;elle a apprise lorsqu\u2019elle \u00e9tait enfant et qu\u2019elle parle encore cette langue couramment.<br \/>\n[\/et_pb_accordion_item][et_pb_accordion_item title=\u00a0\u00bbJ\u2019ai entendu parler de \u00ab traduction automatique \u00bb. Qu\u2019est-ce que c\u2019est exactement?\u00a0\u00bb _builder_version=\u00a0\u00bb3.0.47&Prime; open=\u00a0\u00bboff\u00a0\u00bb]Sommairement, l\u2019expression <em>traduction automatique<\/em> fait r\u00e9f\u00e9rence \u00e0 la traduction d\u2019un texte par un logiciel qui ne poss\u00e8de pas les facult\u00e9s de logique, de coh\u00e9rence et de cr\u00e9ativit\u00e9 propres au g\u00e9nie humain.<br \/>\n[\/et_pb_accordion_item][et_pb_accordion_item title=\u00a0\u00bbAvez-vous recours \u00e0 la traduction automatique pour traduire les documents que vos clients vous confient?\u00a0\u00bb _builder_version=\u00a0\u00bb3.0.47&Prime; open=\u00a0\u00bboff\u00a0\u00bb] Non, en aucune fa\u00e7on. [\/et_pb_accordion_item][\/et_pb_accordion][et_pb_text admin_label=\u00a0\u00bb5 &#8211; NOTRE ENTREPRISE\u00a0\u00bb _builder_version=\u00a0\u00bb3.27.4&Prime; text_font=\u00a0\u00bbOpen Sans||||\u00a0\u00bb text_font_size=\u00a0\u00bb16&Prime; text_line_height=\u00a0\u00bb1.8em\u00a0\u00bb background_size=\u00a0\u00bbinitial\u00a0\u00bb background_position=\u00a0\u00bbtop_left\u00a0\u00bb background_repeat=\u00a0\u00bbrepeat\u00a0\u00bb use_border_color=\u00a0\u00bboff\u00a0\u00bb border_color=\u00a0\u00bb#ffffff\u00a0\u00bb border_style=\u00a0\u00bbsolid\u00a0\u00bb]<\/p>\n<p>\n<a name=\"entreprise\"><\/a><\/p>\n<h3 id=\"faq-005\">5 &#8211; NOTRE ENTREPRISE<\/h3>\n<p>[\/et_pb_text][et_pb_accordion _builder_version=\u00a0\u00bb3.0.87&Prime; use_border_color=\u00a0\u00bboff\u00a0\u00bb border_color=\u00a0\u00bb#ffffff\u00a0\u00bb border_style=\u00a0\u00bbsolid\u00a0\u00bb][et_pb_accordion_item title=\u00a0\u00bbPourquoi avez-vous choisi Traduction INVISIBLE comme nom d\u2019entreprise?\u00a0\u00bb _builder_version=\u00a0\u00bb3.0.47&Prime; open=\u00a0\u00bbon\u00a0\u00bb]Nous sommes d\u2019avis que la traduction d\u2019un \u00e9crit doit \u00eatre invisible lorsqu\u2019elle est compar\u00e9e \u00e0 l\u2019original. En d\u2019autres mots, nous croyons que le lecteur ne doit pas se douter que le texte qu\u2019il lit est une traduction. Nous vous invitons \u00e0 vous rendre \u00e0 <a href=\"https:\/\/www.invisibletranslation.com\/fr\/faq\/notre-vision\/\">cette page<\/a> si vous voulez mieux comprendre le concept qui est \u00e0 l\u2019origine du nom de notre entreprise.<br \/>\n[\/et_pb_accordion_item][et_pb_accordion_item title=\u00a0\u00bbO\u00f9 puis-je trouver un r\u00e9sum\u00e9 complet des services que vous offrez?\u00a0\u00bb _builder_version=\u00a0\u00bb3.0.47&Prime; open=\u00a0\u00bboff\u00a0\u00bb]Vous n\u2019avez qu\u2019\u00e0 consulter <a href=\"https:\/\/www.invisibletranslation.com\/fr\/services\/\">cette page<\/a>. Vous pourrez notamment apprendre la diff\u00e9rence entre la r\u00e9vision unilingue et bilingue, ou en savoir plus sur nos services d\u2019experts-conseils.<br \/>\n[\/et_pb_accordion_item][et_pb_accordion_item title=\u00a0\u00bbAvez-vous compil\u00e9 une liste des avantages que vous offrez \u00e0 votre client\u00e8le?\u00a0\u00bb _builder_version=\u00a0\u00bb3.0.47&Prime; open=\u00a0\u00bboff\u00a0\u00bb]Oui, nous avons pr\u00e9par\u00e9 <a href=\"https:\/\/www.invisibletranslation.com\/fr\/a-propos\/pourquoi-choisir-traduction-invisible\/\">une page<\/a> \u00e0 cet effet. Vous constaterez que nous offrons des tarifs concurrentiels et des avantages bien r\u00e9els qui vous permettront de maximiser le rendement de votre investissement tout en obtenant un service professionnel d\u2019une qualit\u00e9 in\u00e9gal\u00e9e.<br \/>\n[\/et_pb_accordion_item][et_pb_accordion_item title=\u00a0\u00bbO\u00f9 sont situ\u00e9s vos bureaux?\u00a0\u00bb _builder_version=\u00a0\u00bb3.0.47&Prime; open=\u00a0\u00bboff\u00a0\u00bb]Notre si\u00e8ge social se trouve en plein centre-ville de Granby, pr\u00e8s de Montr\u00e9al, au c\u0153ur de la Mont\u00e9r\u00e9gie, dans la province de Qu\u00e9bec, au Canada, \u00e0 moins d\u2019une heure de la fronti\u00e8re des \u00c9tats-Unis.<br \/>\n[\/et_pb_accordion_item][\/et_pb_accordion][et_pb_text admin_label=\u00a0\u00bb6 &#8211; SI J\u2019AI D\u2019AUTRES QUESTIONS?\u00a0\u00bb _builder_version=\u00a0\u00bb3.27.4&Prime; text_font=\u00a0\u00bbOpen Sans||||\u00a0\u00bb text_font_size=\u00a0\u00bb16&Prime; text_line_height=\u00a0\u00bb1.8em\u00a0\u00bb background_size=\u00a0\u00bbinitial\u00a0\u00bb background_position=\u00a0\u00bbtop_left\u00a0\u00bb background_repeat=\u00a0\u00bbrepeat\u00a0\u00bb use_border_color=\u00a0\u00bboff\u00a0\u00bb border_color=\u00a0\u00bb#ffffff\u00a0\u00bb border_style=\u00a0\u00bbsolid\u00a0\u00bb]<\/p>\n<p>\n<a name=\"questions\"><\/a><\/p>\n<h3 id=\"faq-006\">6 &#8211; SI J\u2019AI D\u2019AUTRES QUESTIONS?<\/h3>\n<p>[\/et_pb_text][et_pb_text _builder_version=\u00a0\u00bb3.27.4&Prime; background_size=\u00a0\u00bbinitial\u00a0\u00bb background_position=\u00a0\u00bbtop_left\u00a0\u00bb background_repeat=\u00a0\u00bbrepeat\u00a0\u00bb use_border_color=\u00a0\u00bboff\u00a0\u00bb border_color=\u00a0\u00bb#ffffff\u00a0\u00bb border_style=\u00a0\u00bbsolid\u00a0\u00bb]<\/p>\n<p>\nT\u00e9l\u00e9phonez-nous sans tarder en composant le num\u00e9ro suivant\u00a0: <a href=\"tel:18334366331\">+1\u00a0833-436-6331<\/a>. Vous pouvez aussi communiquer avec nous par courrier \u00e9lectronique\u00a0: <a href=\"mailto:questions@traductioninvisible.com\">questions@traductioninvisible.com<\/a>. Nous vous invitons \u00e9galement \u00e0 nous transmettre vos commentaires et vos suggestions pour que nous puissions mieux vous servir\u00a0: <a href=\"mailto:info@traductioninvisible.com?subject=Commentaires%20-%20FAQ\">info@traductioninvisible.com<\/a>.<\/p>\n<p>[\/et_pb_text][\/et_pb_column][et_pb_column type=\u00a0\u00bb1_3&Prime; _builder_version=\u00a0\u00bb3.25&Prime; custom_padding=\u00a0\u00bb|||\u00a0\u00bb custom_padding__hover=\u00a0\u00bb|||\u00a0\u00bb][et_pb_sidebar orientation=\u00a0\u00bbright\u00a0\u00bb area=\u00a0\u00bbsidebar-1&Prime; _builder_version=\u00a0\u00bb3.0.74&Prime; remove_border=\u00a0\u00bboff\u00a0\u00bb][\/et_pb_sidebar][\/et_pb_column][\/et_pb_row][\/et_pb_section]<\/p>\n","protected":false},"excerpt":{"rendered":"<p><nav aria-label=\"breadcrumbs\" class=\"rank-math-breadcrumb\"><p><span class=\"last\">Home<\/span><\/p><\/nav> Foire aux questions 1 &#8211; Renseignements pratiques 2 &#8211; Notre \u00e9quipe 3 &#8211; D\u00e9lais et tarifs 4 &#8211; Qualit\u00e9 et efficacit\u00e9 5 &#8211; Notre entreprise 6 &#8211; Autres questions 1 &#8211; RENSEIGNEMENTS PRATIQUES Non, Traduction INVISIBLE est bien plus qu\u2019une simple agence de traduction. Nous offrons des services de traduction, d\u2019adaptation publicitaire, de r\u00e9vision [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":0,"parent":0,"menu_order":5,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_et_pb_use_builder":"on","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[],"tags":[],"class_list":["post-1368","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/www.invisibletranslation.com\/fr\/wp-json\/wp\/v2\/pages\/1368","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.invisibletranslation.com\/fr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.invisibletranslation.com\/fr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.invisibletranslation.com\/fr\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.invisibletranslation.com\/fr\/wp-json\/wp\/v2\/comments?post=1368"}],"version-history":[{"count":0,"href":"https:\/\/www.invisibletranslation.com\/fr\/wp-json\/wp\/v2\/pages\/1368\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.invisibletranslation.com\/fr\/wp-json\/wp\/v2\/media?parent=1368"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.invisibletranslation.com\/fr\/wp-json\/wp\/v2\/categories?post=1368"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.invisibletranslation.com\/fr\/wp-json\/wp\/v2\/tags?post=1368"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}